{"id":2207,"date":"2025-01-21T08:00:00","date_gmt":"2025-01-21T07:00:00","guid":{"rendered":"https:\/\/www.fuhselab.de\/?p=2207"},"modified":"2026-06-30T11:37:58","modified_gmt":"2026-06-30T09:37:58","slug":"arduino-infrarot-fernbedienung-3","status":"publish","type":"post","link":"https:\/\/www.fuhselab.de\/index.php\/2025\/01\/21\/arduino-infrarot-fernbedienung-3\/","title":{"rendered":"Arduino Infrarot Fernbedienung (3)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Die Arduino Infrarot Fernbedienung wird weiter optimiert und angepasst. Der Code aus der letzten Woche soll nun also so modifiziert werden, um das zu machen was er machen soll&#8230;<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aufgabenstellung:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Infrarot-Projekt soll folgende Aufgabe erf\u00fcllen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 1 = rote LED leuchtet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 2 = gr\u00fcne LED leuchtet<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 3 = rote und gr\u00fcne LED leuchten<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 4 = rote LED blinkt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 5 = gr\u00fcne LED blinkt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taste 6 = rote und gr\u00fcne LED blinken<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als IR-Receiver kommt auch immer noch der <a href=\"https:\/\/www.reichelt.de\/ir-empfaenger-module-30khz-90-side-view-tsop-4830-p158400.html?CCOUNTRY=445&amp;LANGUAGE=de&amp;trstct=pos_0&amp;nbc=1&amp;&amp;r=1\">TSOP 4830<\/a> zum Einsatz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die Fernbedienung und die Sache mit den IR-Codes:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr dieses Projekt wird eine Fernbedienung ben\u00f6tigt, die sich auf die Sony-Codes einstellen l\u00e4sst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Druck auf Taste 1 erzeugt den Hex-Wert 10. Ein Druck auf Taste 5 sollte den Hex-Wert 210 ergeben. Da ich mich f\u00fcr eine Vivanco-Fernbedienung entschieden habe: Set und TV1-Taste dr\u00fccken bis rote LED leuchtet und Code 045 einstellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programmierung:<\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>int led01 = 2;   \/\/LED 1 an digitalen Pin 2 angeschlossen\nint led02 = 3;   \/\/LED 2 an digitalen Pin 3 angeschlossen\n\nint receiverpin =11;\n#include &lt;IRremote.h>\nIRrecv irrecv(receiverpin);\ndecode_results results;\n\nvoid setup()\n{\nirrecv.enableIRIn();\n\/\/ for-Schleife gel\u00f6scht\npinMode(2, OUTPUT);\npinMode(3, OUTPUT);\n}\n\nvoid translateIR()\n{\nswitch(results.value)\n{\ncase 0x810: pinOn(2);\nbreak;\ncase 0x410: pinOn(3);\nbreak;\ncase 0xC10: pinOn(4);\nbreak;\ncase 0x210: pinOn(5);\nbreak;\ncase 0xA10: pinOn(6);\nbreak;\ncase 0x610: pinOn(7);\nbreak; \n}\n}\n\nvoid pinOn(int pin)\n{\ndigitalWrite(pin, HIGH);\n}\n\nvoid loop()\n{\nif(irrecv.decode(&amp;results))\n{\ntranslateIR();\nfor (int z = 0 ; z &lt; 2 ; z++)\n{\nirrecv.resume();\n}\n}\n}<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Die letzten beiden Codes, also der aus dem letzten Artikel und der Code aus diesem Artikel, schalten die LEDs leider noch nicht aus und sind somit noch fehlerhaft weil sie nicht das machen was sie machen sollen. Trotzdem wollte ich meine Versuche auf dem Weg zur Infrarot Fernbedienung hier dokumentieren. Die Experimente werden also weitergehen&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Arduino Infrarot Fernbedienung wird weiter optimiert und angepasst. Der Code aus der letzten Woche soll nun also so modifiziert werden, um das zu machen was er machen soll&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[22],"class_list":["post-2207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arduino","tag-arduino-gruppe-peine"],"_links":{"self":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/2207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/comments?post=2207"}],"version-history":[{"count":1,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/2207\/revisions"}],"predecessor-version":[{"id":2208,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/2207\/revisions\/2208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/media?parent=2207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/categories?post=2207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/tags?post=2207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}