{"id":1437,"date":"2024-06-11T08:00:00","date_gmt":"2024-06-11T06:00:00","guid":{"rendered":"https:\/\/www.fuhselab.de\/?p=1437"},"modified":"2026-06-30T10:50:47","modified_gmt":"2026-06-30T08:50:47","slug":"arduino-radioschalter","status":"publish","type":"post","link":"https:\/\/www.fuhselab.de\/index.php\/2024\/06\/11\/arduino-radioschalter\/","title":{"rendered":"Arduino Radioschalter"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nach den Arduino Projekten mit Tastenfeldern geht es in diesem Artikel mit einem Radioschalter weiter&#8230;<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was ist eigentlich ein Radioschalter?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einem ersten Schritt sollte gekl\u00e4rt werden, was hier mit einem Radioschalter gemeint ist. Bei dem folgenden Projekt kommt ein Schalter zum Einsatz der aus mehreren einzelnen Schaltern besteht die miteinander verbunden sind. Wie bei alten Radios l\u00e4sst sich immer nur ein Schalter aktivieren und die anderen springen dann automatisch raus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der Hardwareaufbau f\u00fcr den Radioschalter:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verbindung der Schalter mit den Arduino Pins&#8230;.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Radioschalter<\/td><td>Arduino Pin<\/td><\/tr><tr><td>1 (wei\u00dfes Kabel links au\u00dfen f\u00fcr Schalter 1)<\/td><td>&#8230;\u00fcber 10kOhm an Ground und Pin 2<\/td><\/tr><tr><td>2 (rotes Kabel f\u00fcr Schalter 2)<\/td><td>&#8230;\u00fcber 10kOhm an Ground und Pin 3<\/td><\/tr><tr><td>3 (gr\u00fcnes Kabel f\u00fcr Schalter 3)<\/td><td>&#8230;\u00fcber 10kOhm an Ground und Pin 4<\/td><\/tr><tr><td>4 (wei\u00dfes Kabel f\u00fcr Schalter 4)<\/td><td>&#8230;\u00fcber 10kOhm an Ground und Pin 5<\/td><\/tr><tr><td>5 (schwarzes Kabel)<\/td><td>5 Volt<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Am Arduino werden noch drei LEDs an Arduino Pin 13, 12 und 11 angeschlossen mit 560 Ohm Widerstand zwischen LED und den Arduino-Pins (hier 11, 12, 13).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der Arduino Code f\u00fcr den Radioschalter:<\/strong><\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>int schalter01 = 2;\nint schalter02 = 3;\nint schalter03 = 4;\nint schalter04 = 5;\n\nint led01 = 13;\nint led02 = 12;\nint led03 = 11;\n\n\nint buttonState01 = 0;\nint buttonState02 = 0;\nint buttonState03 = 0;\nint buttonState04 = 0;\n\nvoid setup() {\n\npinMode(led01, OUTPUT);\npinMode(led02, OUTPUT);\npinMode(led03, OUTPUT);\npinMode(schalter01, INPUT);\npinMode(schalter02, INPUT);\npinMode(schalter03, INPUT);\npinMode(schalter04, INPUT);\n}\n\nvoid loop(){\n\nbuttonState01 = digitalRead(schalter01);\nbuttonState02 = digitalRead(schalter02);\nbuttonState03 = digitalRead(schalter03);\nbuttonState04 = digitalRead(schalter04);\n\n\nif (buttonState01 == HIGH) {     \ndigitalWrite(led01, HIGH);  \n} \nelse {\ndigitalWrite(led01, LOW); \n}\n\nif (buttonState02 == HIGH) {     \ndigitalWrite(led02, HIGH);  \n} \nelse {\ndigitalWrite(led02, LOW); \n}\n\nif (buttonState03 == HIGH) {     \ndigitalWrite(led03, HIGH);  \n} \nelse {\ndigitalWrite(led03, LOW); \n}\n\n} \/* abschlie\u00dfende Klammer von void loop nicht l\u00f6schen  *\/<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach den Arduino Projekten mit Tastenfeldern geht es in diesem Artikel mit einem Radioschalter weiter&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[22],"class_list":["post-1437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arduino","tag-arduino-gruppe-peine"],"_links":{"self":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/1437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/comments?post=1437"}],"version-history":[{"count":2,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/1437\/revisions"}],"predecessor-version":[{"id":2793,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/posts\/1437\/revisions\/2793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/media?parent=1437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/categories?post=1437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fuhselab.de\/index.php\/wp-json\/wp\/v2\/tags?post=1437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}